{"id":15965,"date":"2021-08-02T10:56:00","date_gmt":"2021-08-02T14:56:00","guid":{"rendered":"https:\/\/www.motionlaw.com\/?p=15965"},"modified":"2021-08-02T10:56:00","modified_gmt":"2021-08-02T14:56:00","slug":"senador-apoya-proteccion-para-inmigrantes-esenciales","status":"publish","type":"post","link":"https:\/\/www.motionlaw.com\/es\/senador-apoya-proteccion-para-inmigrantes-esenciales\/","title":{"rendered":"Senador Apoya Protecci\u00f3n Para Inmigrantes Esenciales"},"content":{"rendered":"<h1><span style=\"color: #161b33;\">Senador apoya planes migratorios de Biden y pide protecci\u00f3n para trabajadores esenciales<\/span><\/h1>\n<p>La semana pasada, el presidente Joe Biden y la vicepresidenta Kamala Harris se reunieron con varios l\u00edderes Dem\u00f3cratas para discutir acerca de la reforma migratoria integral, el proyecto de reconciliaci\u00f3n presupuestaria y el camino a la ciudadan\u00eda para trabajadores esenciales indocumentados.<\/p>\n<p>El Presidente de la Subcomisi\u00f3n Judicial del Senado, el Senador Alex Padilla, emiti\u00f3 <span style=\"color: #003366;\"><a style=\"color: #003366;\" href=\"https:\/\/goldrushcam.com\/sierrasuntimes\/index.php\/news\/local-news\/31672-u-s-senator-alex-padilla-s-statement-on-white-house-immigration-meeting-says-we-must-fight-for-permanent-protections-for-the-immigrants-whose-contributions-are-essential-to-our-nation-s-economy-and-security\" target=\"_blank\" rel=\"noopener noreferrer\">un comunicado<\/a><\/span> despu\u00e9s de la reuni\u00f3n con el presidente Biden y declar\u00f3 que los l\u00edderes dem\u00f3cratas se sienten bastante esperanzados con promover la reforma migratoria integral a trav\u00e9s del proceso de reconciliaci\u00f3n.<\/p>\n<p>A grandes rasgos, el proceso de reconciliaci\u00f3n le permitir\u00eda a la administraci\u00f3n de Biden incluir una legislaci\u00f3n de inmigraci\u00f3n en un paquete presupuestario, el cual podr\u00eda ser aprobado por el Senado (la c\u00e1mara alta del Congreso) sin necesidad de obtener 60 votos, sino solo 51.<\/p>\n<p>Con respecto a esta opci\u00f3n, Padilla declar\u00f3 abiertamente que <em>\u201cEste es un momento cr\u00edtico para el futuro de la reforma migratoria. El pr\u00f3ximo proceso de reconciliaci\u00f3n presupuestaria nos brinda la mejor oportunidad que hemos tenido en a\u00f1os para actuar\u201d<\/em>.<\/p>\n<p>A\u00f1adiendo a eso, Padilla enfatiz\u00f3 en la importancia de apoyar la reforma migratoria, inclusive a trav\u00e9s del proceso de reconciliaci\u00f3n, especialmente teniendo en cuenta que Estados Unidos est\u00e1 intentando recuperarse de la crisis econ\u00f3mica tra\u00edda por la pandemia global de Coronavirus y, por ende, es importante proteger a los trabajadores esenciales alrededor de la naci\u00f3n, incluyendo a los inmigrantes indocumentados, quienes prestan sus servicios en toda clase de sectores del mercado local y mantienen a flote la econom\u00eda del pa\u00eds.<\/p>\n<p>\u00a1<span style=\"color: #003366;\"><strong><a style=\"color: #003366;\" href=\"https:\/\/www.motionlaw.com\/es\/contactenos\/\">Contacte a Motion Law Immigration<\/a><\/strong><\/span> e inicie su viaje de inmigraci\u00f3n con nuestros abogados experimentados a trav\u00e9s de una Consulta GRATUITA!<\/p>\n<h2>Administraci\u00f3n de Biden avanza sobre la inmigraci\u00f3n a pesar de controversia<\/h2>\n<p>No es un secreto que la situaci\u00f3n fronteriza actual representa un reto gigantesco para la administraci\u00f3n actual de los Estados Unidos e inclusive un riesgo para los planes migratorios de Biden. Con esto, hacemos referencia a una oleada de cruces ilegales en las fronteras que ha tenido lugar desde finales del 2020, pero que increment\u00f3 substancialmente desde inicios del 2021, justo cuando el presidente Biden asumi\u00f3 el cargo.<\/p>\n<p>Sin embargo, a pesar de la controversia social que est\u00e1 enfrentando, la administraci\u00f3n de Biden a\u00fan contin\u00faa con el prop\u00f3sito de reestructurar el sistema de inmigraci\u00f3n entero a trav\u00e9s de m\u00faltiples estrategias, que incluyen, pero no se limitan a:<\/p>\n<ul>\n<li>Remover, levantar o rescindir pol\u00edticas y restricciones implementadas por la administraci\u00f3n de Trump sobre toda clase de procesos de inmigraci\u00f3n.<\/li>\n<li>Remodelar el proceso de asilo pol\u00edtico y otros programas humanitarios.<\/li>\n<li>Aplicar la ley de inmigraci\u00f3n en el territorio fronterizo por medio de pol\u00edticas humanas y justas.<\/li>\n<li>Promover una reforma migratoria integral en el Congreso.<\/li>\n<li>Expandir las alternativas disponibles para trabajadores extranjeros, lo que incluye trabajadores agr\u00edcolas indocumentados, trabajadores extranjeros altamente cualificados, trabajadores esenciales para el sistema de salud o la cadena de suministros de alimentos de los Estados Unidos, entre otros.<\/li>\n<\/ul>\n<p>En otras palabras, la administraci\u00f3n de Biden est\u00e1 avanzando sobre el sistema de inmigraci\u00f3n a pesar del debate social relacionado con la situaci\u00f3n fronteriza actual.<\/p>\n<p>\u00bfNecesita ayuda con un caso de inmigraci\u00f3n de cualquier \u00edndole? Nuestro equipo puede ayudarle. \u00a1<span style=\"color: #003366;\"><strong><a style=\"color: #003366;\" href=\"https:\/\/www.motionlaw.com\/es\/contactenos\/\">Contacte a Motion Law Immigration<\/a><\/strong><\/span>, programe una Consulta GRATUITA y siga el consejo de nuestros abogados experimentados!<\/p>\n<h2>\u00a1Siga el consejo de expertos para tener un proceso de inmigraci\u00f3n exitoso!<\/h2>\n<p>Nosotros queremos ayudarle a cumplir sus sue\u00f1os en los Estados Unidos a trav\u00e9s del proceso de inmigraci\u00f3n que mejor se acomode a sus necesidades actuales. Por lo tanto, no dude en contactar a Motion Law Immigration, programe una <span style=\"color: #003366;\"><strong><a style=\"color: #003366;\" href=\"https:\/\/www.motionlaw.com\/es\/\">Consulta GRATUITA<\/a><\/strong><\/span> y siga el consejo de nuestros <span style=\"color: #003366;\"><a style=\"color: #003366;\" href=\"https:\/\/www.motionlaw.com\/es\/contactenos\/\">abogados expertos en inmigraci\u00f3n<\/a><\/span>, quienes tienen una vasta experiencia con toda clase de casos de inmigraci\u00f3n y seguramente sabr\u00e1n cu\u00e1l es la mejor alternativa para su caso particular.<\/p>\n<p>Simplemente llame a Motion Law hoy al: <strong>(202) 918-1799.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Senador apoya planes migratorios de Biden y pide protecci\u00f3n para trabajadores esenciales La semana pasada, el presidente Joe Biden y la vicepresidenta Kamala Harris se reunieron con varios l\u00edderes Dem\u00f3cratas para discutir acerca de la reforma migratoria integral, el proyecto de reconciliaci\u00f3n presupuestaria y el camino a la ciudadan\u00eda para trabajadores esenciales indocumentados. El Presidente&hellip;<\/p>\n","protected":false},"author":16,"featured_media":15966,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1690,89],"tags":[],"yst_prominent_words":[749,2276,8359,8424],"class_list":["post-15965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ley-de-inmigracion","category-noticias-de-inmigracion"],"jetpack_featured_media_url":"https:\/\/www.motionlaw.com\/wp-content\/uploads\/Senador-Apoya-Proteccion-Para-Inmigrantes-Esenciales.png","jetpack_shortlink":"https:\/\/wp.me\/p93TlB-49v","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/posts\/15965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/comments?post=15965"}],"version-history":[{"count":1,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/posts\/15965\/revisions"}],"predecessor-version":[{"id":15968,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/posts\/15965\/revisions\/15968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/media\/15966"}],"wp:attachment":[{"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/media?parent=15965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/categories?post=15965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/tags?post=15965"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.motionlaw.com\/es\/wp-json\/wp\/v2\/yst_prominent_words?post=15965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}